{"id":9762,"date":"2019-01-02T11:33:09","date_gmt":"2019-01-02T10:33:09","guid":{"rendered":"http:\/\/www.hundevereinarheilgen.de\/WP3\/?p=9762"},"modified":"2019-01-02T11:35:00","modified_gmt":"2019-01-02T10:35:00","slug":"6-oarhelljer-fun-cup-rally-obedience-am-31-03-2019","status":"publish","type":"post","link":"https:\/\/www.hundevereinarheilgen.de\/WP3\/2019\/01\/6-oarhelljer-fun-cup-rally-obedience-am-31-03-2019\/","title":{"rendered":"6. Oarhelljer Fun Cup (Rally Obedience) am 31.03.2019"},"content":{"rendered":"<p>Die Einladung f\u00fcr den 6. Oarhelljer Fun Cup ist nun online.<br \/>\nSie finden die Einladung unter <a href=\"https:\/\/www.hundevereinarheilgen.de\/WP3\/prufungen\/\">Pr\u00fcfungen und Wettk\u00e4mpfe<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Einladung f\u00fcr den 6. Oarhelljer Fun Cup ist nun online. Sie finden die Einladung unter Pr\u00fcfungen und Wettk\u00e4mpfe.<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"Die Einladung f\u00fcr die kommende Veranstaltung ist nun online.\r\nSie finden die Einladung unter Pr\u00fcfungen und Wettk\u00e4mpfe.","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1,12],"tags":[],"class_list":["post-9762","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-rally-obedience"],"_links":{"self":[{"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/posts\/9762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/comments?post=9762"}],"version-history":[{"count":3,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/posts\/9762\/revisions"}],"predecessor-version":[{"id":9803,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/posts\/9762\/revisions\/9803"}],"wp:attachment":[{"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/media?parent=9762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/categories?post=9762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hundevereinarheilgen.de\/WP3\/wp-json\/wp\/v2\/tags?post=9762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}